{"id":7820,"date":"2019-09-19T14:36:58","date_gmt":"2019-09-19T12:36:58","guid":{"rendered":"https:\/\/audiologyblog.phonakpro.com\/?p=7820"},"modified":"2021-11-30T10:17:44","modified_gmt":"2021-11-30T09:17:44","slug":"ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen","status":"publish","type":"post","link":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/","title":{"rendered":"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen"},"content":{"rendered":"<p>Wie oft arbeiten Sie mit einem Kunden zusammen, der sagt: &#8222;Mein Sohn wollte mit mir zur heutigen H\u00f6rger\u00e4teanpassung kommen, aber er musste arbeiten.&#8220;, oder &#8222;Meine Tochter lebt weit weg und kann nicht dabei sein.&#8220; Auch wenn wir uns vornehmen, FCC als festen Bestandteil in die H\u00f6rger\u00e4teversorgung zu integrieren, drohen wir regelm\u00e4\u00dfig an der Realit\u00e4t zu scheitern. Wir k\u00f6nnen zwar unsere Kunden aktiv ermutigen, ihre Familie zu Terminen bei uns mitzubringen, aber immer wieder klappt es aufgrund von Zeitmangel, geografischen Entfernungen oder auch Krankheit einfach nicht. In Wirklichkeit liegt aber genau hier die gro\u00dfe Chance \u2013 indem wir moderne Technologien nutzen, um diese H\u00fcrden zu \u00fcberwinden und die Familie in den Termin zu integrieren.<\/p>\n<p><strong>FCC und eAudiology \u2013 in Kombination zum Erfolg<\/strong><\/p>\n<p>Vor kurzem hat Phonak zwei Expertenpanels zu praxisrelevanten Themen der Audiologie einberufen: FCC und eAudiology. Das FCC-Panel hat es sich zum Ziel gesetzt, die Einbindung der Familie in der H\u00f6rger\u00e4teversorgung zu f\u00f6rdern (Singh, G. et al 2016) \u2013 und hat daf\u00fcr ein spezielles Konzept entwickelt und sich der Aufkl\u00e4rung zu diesem Thema verschrieben. Das eAudiology-Panel hat ein Positionspapier entwickelt, das Empfehlungen zur Umsetzung im Fachgesch\u00e4ft wie bspw. zur Neukundengewinnung, zur Verbesserung der Versorgung und zur Steigerung des Wertes der erbrachten Dienstleistungen umfasst (Montano, et al, 2018). Wir haben nun die M\u00f6glichkeit, die Themen und Erkenntnisse der beiden Expertenpanels zu kombinieren und Technologie gezielt einzusetzen, um Familienmitgliedern die Teilnahme an Versorgungsterminen zu erleichtern.<\/p>\n<p><strong>Aus der Distanz dabei \u2013 genauso effektiv eingebunden<\/strong><\/p>\n<p>Neulich hatte ich einen Kunden f\u00fcr eine H\u00f6rger\u00e4teberatung und -anpassung im Fachgesch\u00e4ft, der von seiner Frau, seinem erwachsenen Sohn und seiner Tochter begleitet wurde. Die Familie war eng in die Versorgungsentscheidung eingebunden. Kurz nachdem wir einen Folgetermin vereinbart hatten, brach sich seine Tochter das Bein, so dass sie den n\u00e4chsten Termin vor Ort nicht wahrnehmen konnte. Der Kunde fragte, ob wir sie telefonisch mit dazu holen k\u00f6nnten. Ich schlug daraufhin vor, dass wir sie nicht nur anrufen, sondern FaceTime verwenden k\u00f6nnten, da sie beide iPhones hatten. Das Ergebnis: Die Tochter konnte bei der Nachsorge wieder mit dabei sein, sie unterst\u00fctzte ihren Vater mit Lob und freute sich direkt mit f\u00fcr den Erfolg, den er mit seinen H\u00f6rger\u00e4ten erzielt hatte. Ein wirklich lohnender und emotionaler Moment!<\/p>\n<p><strong>Videoschaltungen \u2013 eine unkomplizierte L\u00f6sung<\/strong><\/p>\n<p>Wenn wir unsere Kunden dazu ermutigen, die Familie mit einzubeziehen, brauchen wir nat\u00fcrlich auch eine L\u00f6sung, wenn Termine und gr\u00f6\u00dfere Distanzen dazwischenkommen. Die meisten Menschen haben heute Zugriff auf eine Videokonferenz-Anwendung, sei es Skype, WhatsApp oder FaceTime. Schlagen Sie Ihren Kunden vor, dass Sie die Familie auf diesem Weg an der Beratung teilnehmen lassen. Was das f\u00fcr Sie konkret bedeutet? Sie vereinbaren einen Termin, kl\u00e4ren den Zugang zur Videotechnik ab, stellen die Verbindung her und begr\u00fc\u00dfen Sie die Familie (wie vor Ort) zum Termin. Es ist wirklich einfach und unkompliziert, wenn man es erst einmal ausprobiert hat. Und glauben Sie mir, es lohnt sich f\u00fcr alle: f\u00fcr Ihren Kunden, f\u00fcr die Familie und f\u00fcr Sie!<\/p>\n<p>Weitere Informationen und Einblicke, wie digitale Services die H\u00f6rger\u00e4teversorgung unterst\u00fctzen k\u00f6nnen, finden Sie auf der <a href=\"https:\/\/www.phonakpro.com\/ch\/de\/ressourcen\/beratungsinstrumente\/eAudiology\/overview-eaudiology.html\">eAudiology-Unterseite<\/a> unserer Website. Mehr \u00fcber Family-Centered Care erfahren Sie auf unserer <a href=\"https:\/\/www.phonakpro.com\/ch\/de\/ressourcen\/beratungsinstrumente\/family-centered-care.html\">FCC-Unterseite<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10pt;\"><strong>Referenzen<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Montano, J., Angley, G., Ryan-Bane, C., Ryan-Bane, C., Campbell, W., Eikelboom, R. , Gerlach, A., Glista, D., Mu\u00f1oz, K., Jones, C., Ferguson, M., Swanepoel, DW., Buerkli-Halevy, O., Singh, G., Omisore, D., Schuepbach-Wolf &amp; Julita, F. (2018). eAudiology: Shifting from theory to practice.&nbsp;<em>Hearing Review&nbsp;<\/em>;25(9):20-24.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Singh, G., Hickson, L., English, K., Scherpiet, S., Lemke, U., Timmer, B., Buerkli-Halevy, O., Montano, J., Preminger, J., Scarinci, N., Saunders, G., Jennings, M.B., &amp; Launer, S. (2016). Family-Centered Adult Audiologic Care: A Phonak Position Statement.&nbsp;<em>Hearing Review<\/em>;23(4):16.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Zeitdruck und gr\u00f6\u00dfere Distanzen die Teilnahme der Familie an der Beratung verhindern, bietet die Digitalisierung H\u00f6rakustikern eine einfache und unkomplizierte L\u00f6sung.<\/p>\n","protected":false},"author":66,"featured_media":528086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-7820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-family-centered-care-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen | Audiology Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen | Audiology Blog\" \/>\n<meta property=\"og:description\" content=\"Wenn Zeitdruck und gr\u00f6\u00dfere Distanzen die Teilnahme der Familie an der Beratung verhindern, bietet die Digitalisierung H\u00f6rakustikern eine einfache und unkomplizierte L\u00f6sung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\" \/>\n<meta property=\"og:site_name\" content=\"Phonak Audiology Blog - Phonak Pro - life is on\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/phonak\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-19T12:36:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-30T09:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t<meta property=\"og:image:height\" content=\"1070\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joseph Montano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@phonak\" \/>\n<meta name=\"twitter:site\" content=\"@phonak\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joseph Montano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\"},\"author\":{\"name\":\"Joseph Montano\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/person\/ea1fb79f6e428d0e6e947e0f51bad05c\"},\"headline\":\"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen\",\"datePublished\":\"2019-09-19T12:36:58+00:00\",\"dateModified\":\"2021-11-30T09:17:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\"},\"wordCount\":649,\"publisher\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg\",\"articleSection\":[\"Family-Centered Care\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\",\"url\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\",\"name\":\"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen | Audiology Blog\",\"isPartOf\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg\",\"datePublished\":\"2019-09-19T12:36:58+00:00\",\"dateModified\":\"2021-11-30T09:17:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage\",\"url\":\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg\",\"contentUrl\":\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg\",\"width\":1890,\"height\":1070,\"caption\":\"technology, communication and people concept - senior woman having video call with happy family on tablet computer at home\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/audiologyblog.phonakpro.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#website\",\"url\":\"https:\/\/audiologyblog.phonakpro.com\/\",\"name\":\"Phonak Audiology Blog - Phonak Pro - life is on\",\"description\":\"1The Phonak Audiology Blog presents audiological topics, research and hearing technology updates from experts at Phonak and across the hearing industry.\",\"publisher\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/audiologyblog.phonakpro.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#organization\",\"name\":\"Phonak Audiology Blog - Phonak Pro - life is on\",\"url\":\"https:\/\/audiologyblog.phonakpro.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2016\/09\/Logo_Phonak_life_is_on_pos_RGB_300dpi.jpg\",\"contentUrl\":\"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2016\/09\/Logo_Phonak_life_is_on_pos_RGB_300dpi.jpg\",\"width\":1630,\"height\":863,\"caption\":\"Phonak Audiology Blog - Phonak Pro - life is on\"},\"image\":{\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/phonak\",\"https:\/\/x.com\/phonak\",\"https:\/\/www.instagram.com\/phonak\",\"https:\/\/www.linkedin.com\/company\/phonak\",\"https:\/\/www.youtube.com\/c\/phonak\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/person\/ea1fb79f6e428d0e6e947e0f51bad05c\",\"name\":\"Joseph Montano\",\"description\":\"Joseph, Ed.D., CCC-A is a Professor of Audiology in Clinical Otolaryngology at Weill Cornell Medical College and Director at the Cornell Hearing and Speech Center. He is also a member of the Phonak Expert Circle on Family-Centered Care.\",\"url\":\"https:\/\/audiologyblog.phonakpro.com\/de\/author\/joseph-montano\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen | Audiology Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/","og_locale":"de_DE","og_type":"article","og_title":"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen | Audiology Blog","og_description":"Wenn Zeitdruck und gr\u00f6\u00dfere Distanzen die Teilnahme der Familie an der Beratung verhindern, bietet die Digitalisierung H\u00f6rakustikern eine einfache und unkomplizierte L\u00f6sung.","og_url":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/","og_site_name":"Phonak Audiology Blog - Phonak Pro - life is on","article_publisher":"https:\/\/www.facebook.com\/phonak","article_published_time":"2019-09-19T12:36:58+00:00","article_modified_time":"2021-11-30T09:17:44+00:00","og_image":[{"width":1890,"height":1070,"url":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg","type":"image\/jpeg"}],"author":"Joseph Montano","twitter_card":"summary_large_image","twitter_creator":"@phonak","twitter_site":"@phonak","twitter_misc":{"Verfasst von":"Joseph Montano","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#article","isPartOf":{"@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/"},"author":{"name":"Joseph Montano","@id":"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/person\/ea1fb79f6e428d0e6e947e0f51bad05c"},"headline":"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen","datePublished":"2019-09-19T12:36:58+00:00","dateModified":"2021-11-30T09:17:44+00:00","mainEntityOfPage":{"@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/"},"wordCount":649,"publisher":{"@id":"https:\/\/audiologyblog.phonakpro.com\/#organization"},"image":{"@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg","articleSection":["Family-Centered Care"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/","url":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/","name":"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen | Audiology Blog","isPartOf":{"@id":"https:\/\/audiologyblog.phonakpro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage"},"image":{"@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg","datePublished":"2019-09-19T12:36:58+00:00","dateModified":"2021-11-30T09:17:44+00:00","breadcrumb":{"@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#primaryimage","url":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg","contentUrl":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2019\/09\/Ein-perfektes-Paar_3-2.jpg","width":1890,"height":1070,"caption":"technology, communication and people concept - senior woman having video call with happy family on tablet computer at home"},{"@type":"BreadcrumbList","@id":"https:\/\/audiologyblog.phonakpro.com\/de\/ein-perfektes-paar-warum-sich-family-centered-care-fcc-und-eaudiology-so-gut-kombinieren-lassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/audiologyblog.phonakpro.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ein perfektes Paar: Warum sich Family-Centered Care (FCC) und eAudiology so gut kombinieren lassen"}]},{"@type":"WebSite","@id":"https:\/\/audiologyblog.phonakpro.com\/#website","url":"https:\/\/audiologyblog.phonakpro.com\/","name":"Phonak Audiology Blog - Phonak Pro - life is on","description":"1The Phonak Audiology Blog presents audiological topics, research and hearing technology updates from experts at Phonak and across the hearing industry.","publisher":{"@id":"https:\/\/audiologyblog.phonakpro.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/audiologyblog.phonakpro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/audiologyblog.phonakpro.com\/#organization","name":"Phonak Audiology Blog - Phonak Pro - life is on","url":"https:\/\/audiologyblog.phonakpro.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/logo\/image\/","url":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2016\/09\/Logo_Phonak_life_is_on_pos_RGB_300dpi.jpg","contentUrl":"https:\/\/audiologyblog.phonakpro.com\/wp-content\/uploads\/2016\/09\/Logo_Phonak_life_is_on_pos_RGB_300dpi.jpg","width":1630,"height":863,"caption":"Phonak Audiology Blog - Phonak Pro - life is on"},"image":{"@id":"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/phonak","https:\/\/x.com\/phonak","https:\/\/www.instagram.com\/phonak","https:\/\/www.linkedin.com\/company\/phonak","https:\/\/www.youtube.com\/c\/phonak"]},{"@type":"Person","@id":"https:\/\/audiologyblog.phonakpro.com\/#\/schema\/person\/ea1fb79f6e428d0e6e947e0f51bad05c","name":"Joseph Montano","description":"Joseph, Ed.D., CCC-A is a Professor of Audiology in Clinical Otolaryngology at Weill Cornell Medical College and Director at the Cornell Hearing and Speech Center. He is also a member of the Phonak Expert Circle on Family-Centered Care.","url":"https:\/\/audiologyblog.phonakpro.com\/de\/author\/joseph-montano\/"}]}},"_links":{"self":[{"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/posts\/7820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/comments?post=7820"}],"version-history":[{"count":12,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/posts\/7820\/revisions"}],"predecessor-version":[{"id":528091,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/posts\/7820\/revisions\/528091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/media\/528086"}],"wp:attachment":[{"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/media?parent=7820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/categories?post=7820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/audiologyblog.phonakpro.com\/de\/wp-json\/wp\/v2\/tags?post=7820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}